{"id":656,"date":"2026-07-24T10:49:24","date_gmt":"2026-07-24T08:49:24","guid":{"rendered":"https:\/\/dezet-solutions.com\/?post_type=product&#038;p=656"},"modified":"2026-08-31T20:59:02","modified_gmt":"2026-08-31T18:59:02","slug":"mk-1200","status":"publish","type":"product","link":"https:\/\/dezet-solutions.com\/de_de\/produkt\/mk-1200\/","title":{"rendered":"BRUTUS 1200 Ferngesteuerter Hybrid &#8211; Schlegelm\u00e4her Hangm\u00e4her Raupenmulcher"},"content":{"rendered":"<p><strong>Produktvorteile:<\/strong><\/p>\n<p>\u2713\u00a0Drehmomentstarker Dieselmotor von KOOP<br \/>\n\u2713\u00a0B\u00fcrstenloser Elektroantrieb<br \/>\n\u2713\u00a0Komfortable Industrie-Funkfernbedienung<br \/>\n\u2713\u00a0Raupenantrieb f\u00fcr maximale Traktion<br \/>\n\u2713\u00a0Ideal f\u00fcr Hanglagen und unwegsames Gel\u00e4nde<br \/>\n\u2713\u00a0Mulchwerk<br \/>\n\u2713\u00a0F\u00fcr dichten Bewuchs\/Str\u00e4ucher bis 200 cm<br \/>\n\u2713\u00a0Hohe Fl\u00e4chenleistung<br \/>\n\u2713\u00a0Wartungsfreundliche Bauweise<br \/>\n\u2713\u00a0Hochwertige Verarbeitung f\u00fcr Gewerbe und Privat<\/p>\n<p><strong>Ideal geeignet f\u00fcr:<\/strong><\/p>\n<ul>\n<li>\u00a0Garten- und Landschaftsbau<\/li>\n<li>\u00a0Kommunen<\/li>\n<li>\u00a0Hausmeisterdienste<\/li>\n<li>\u00a0Obst- und Weinbau<\/li>\n<li>\u00a0Solarparks<\/li>\n<li>\u00a0B\u00f6schungen und Hanglagen<\/li>\n<\/ul>\n<p><strong><br \/>\nTechnische Daten:<\/strong><\/p>\n<p>Modell: MK-1200<\/p>\n<ul>\n<li>Antrieb: Diesel + Elektro (Hybrid)<\/li>\n<li>Leistung: Diesel: 18 PS; Elektro 2 x 850W<\/li>\n<li>B\u00fcrstenlose Antriebsmotoren<\/li>\n<li>Steuerung: Funkfernbedienung<\/li>\n<li>Elektro-Start<\/li>\n<li>Schl\u00fcssel-Start<\/li>\n<li>Elektrische Schnitth\u00f6henverstellung<\/li>\n<li>M\u00e4hbreite: ca. 120 cm<\/li>\n<li>Raupenantrieb<\/li>\n<li>360\u00b0 drehbar<\/li>\n<li>Mulchm\u00e4hwerk<\/li>\n<li>Einsatz auf Steigungen bis ca. 45\u00b0 (100%)<\/li>\n<li>410 kg Betriebsgewicht<\/li>\n<li>bis zu 5 km\/h Geschwindigkeit<\/li>\n<li>Lichtmaschine zum Laden des Akkus (24V, 20 Ah)<\/li>\n<\/ul>\n<p><strong>Unser Service:<\/strong><\/p>\n<p>Als Fachh\u00e4ndler stehen wir Ihnen vor und nat\u00fcrlich auch nach dem Kauf zur Seite:<\/p>\n<p>\u2713 2 Jahre Gew\u00e4hrleistung<br \/>\n\u2713\u00a0Alle Ersatz- und Verschlei\u00dfteile verf\u00fcgbar<br \/>\n\u2713\u00a0Fachkundige Beratung<br \/>\n\u2713\u00a0Technischer Support<br \/>\n\u2713\u00a0Wartungs- und Serviceleistungen<br \/>\n\u2713\u00a0Einweisung bei Abholung auf Wunsch<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MK-1200 Profi-Schlegelm\u00e4her mit Funkfernbedienung | Raupenantrieb | F\u00fcr anspruchsvolles Gel\u00e4nde<\/p>\n<p>Mit dem MK-1200 bieten wir Ihnen einen leistungsstarken, ferngesteuerten Schlegelm\u00e4her f\u00fcr den professionellen Einsatz. Der robuste Raupenantrieb und der kraftvolle Dieselmotor mit 18 PS in Kombination mit einem b\u00fcrstenlosen (brushless) Elektroantrieb erm\u00f6glichen eine pr\u00e4zise und feinf\u00fchlige Funksteuerung und ein sicheres und effizientes Arbeiten \u2013 selbst in schwierigem Gel\u00e4nde.<\/p>\n<p>Ob steile B\u00f6schungen, Obstwiesen, Solarparks oder gro\u00dfe Grundst\u00fccke \u2013 der MK-1200 \u00fcberzeugt durch Zuverl\u00e4ssigkeit, hohe Fl\u00e4chenleistung und einfache Bedienung.<\/p>\n","protected":false},"featured_media":657,"comment_status":"open","ping_status":"closed","template":"","meta":{"saved_in_kubio":false,"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"product_brand":[],"product_cat":[23],"product_tag":[81,82,79,73,80,27,29,24,26,78,31],"class_list":["post-656","product","type-product","status-publish","has-post-thumbnail","product_cat-maehrobotik","product_tag-boeschungsmaeher","product_tag-boeschungsmulcher","product_tag-ferngesteuerterraupenmulcher","product_tag-hangmaeher","product_tag-hangmulcher","product_tag-hybridmaeher","product_tag-mulchmaeher","product_tag-rasenmaeher","product_tag-raupenmaeher","product_tag-raupenmulcher","product_tag-schlegelmaeher","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/dezet-solutions.com\/de_de\/wp-json\/wp\/v2\/product\/656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dezet-solutions.com\/de_de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dezet-solutions.com\/de_de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/dezet-solutions.com\/de_de\/wp-json\/wp\/v2\/comments?post=656"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dezet-solutions.com\/de_de\/wp-json\/wp\/v2\/media\/657"}],"wp:attachment":[{"href":"https:\/\/dezet-solutions.com\/de_de\/wp-json\/wp\/v2\/media?parent=656"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dezet-solutions.com\/de_de\/wp-json\/wp\/v2\/product_brand?post=656"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dezet-solutions.com\/de_de\/wp-json\/wp\/v2\/product_cat?post=656"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dezet-solutions.com\/de_de\/wp-json\/wp\/v2\/product_tag?post=656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}